{"id":6013,"date":"2026-02-03T14:08:16","date_gmt":"2026-02-03T06:08:16","guid":{"rendered":"https:\/\/www.shuliygroup.com\/?p=6013"},"modified":"2026-02-03T15:05:26","modified_gmt":"2026-02-03T07:05:26","slug":"otr-dismantling-machine","status":"publish","type":"post","link":"https:\/\/www.shuliygroup.com\/fr\/otr-dismantling-machine\/","title":{"rendered":"Machine de d\u00e9montage OTR"},"content":{"rendered":"<div class=\"gb-grid-wrapper gb-grid-wrapper-05c7bfd6\"> <div class=\"gb-grid-column gb-grid-column-d018e66d\"><div class=\"gb-container gb-container-d018e66d\">  <div class=\"wp-block-uagb-image uagb-block-8994b114 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine.webp\" alt=\"\" class=\"uag-image-6017\" width=\"720\" height=\"540\" title=\"Machine de d\u00e9montage OTR\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>  <\/div><\/div>  <div class=\"gb-grid-column gb-grid-column-661ae01a\"><div class=\"gb-container gb-container-661ae01a\">  <p class=\"gb-headline gb-headline-4aa90ec7 gb-headline-text\">La machine de d\u00e9montage OTR peut couper et s\u00e9parer les pneus de construction de R35 (2100 mm de diam\u00e8tre) \u00e0 R63 en 4-6 parties, y compris le talon, la bande de roulement et la couronne, pour un traitement ult\u00e9rieur.<\/p>    <p class=\"gb-headline gb-headline-277cf751 gb-headline-text translation-block\">Les machines de d\u00e9montage OTR sont g\u00e9n\u00e9ralement utilis\u00e9es en conjonction avec  broyeurs de pneus  et d'autres \u00e9quipements comme \u00e9tape importante dans une ligne de production de recyclage de pneus OTR.<\/p>  <\/div><\/div> <\/div>   <p class=\"gb-headline gb-headline-bffc845a gb-headline-text translation-block\"><strong>Fonction et application<\/strong><\/p>    <p class=\"gb-headline gb-headline-0dd79f4d gb-headline-text\">La machine de d\u00e9montage OTR est con\u00e7ue pour couper et s\u00e9parer les pneus OTR complets en 4 \u00e0 6 sections, comprenant g\u00e9n\u00e9ralement le talon, la bande de roulement et la couronne. Cette segmentation facilite consid\u00e9rablement les processus ult\u00e9rieurs tels que le broyage ou la s\u00e9paration des mat\u00e9riaux.<\/p>    <div class=\"wp-block-uagb-image uagb-block-c38f9091 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-tire-recycling.webp\" alt=\"\" class=\"uag-image-6019\" width=\"720\" height=\"540\" title=\"Recyclage de pneus OTR\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>    <h2 class=\"wp-block-heading\" style=\"font-size:20px\">Deux mod\u00e8les de machine de d\u00e9montage OTR<\/h2>    <p class=\"gb-headline gb-headline-5aecdb6f gb-headline-text\">Nous proposons deux mod\u00e8les pour s'adapter \u00e0 diff\u00e9rentes tailles de pneus OTR :<\/p>    <ul style=\"font-size:18px\" class=\"wp-block-list\"> <li>Mod\u00e8le 1 : Convient pour les pneus OTR avec un diam\u00e8tre allant de 1400 \u00e0 2000 mm<\/li>    <li>Mod\u00e8le 2 : Con\u00e7u pour des pneus plus grands tels que R35 (environ 2100 mm) \u00e0 R63<\/li> <\/ul>    <p class=\"gb-headline gb-headline-7d94aa70 gb-headline-text\">Les deux mod\u00e8les sont optimis\u00e9s en termes de conception structurelle, de r\u00e9sistance des lames et de syst\u00e8mes de contr\u00f4le pour assurer un fonctionnement s\u00fbr et efficace.<\/p>   <div class=\"gb-grid-wrapper gb-grid-wrapper-e7284d96\"> <div class=\"gb-grid-column gb-grid-column-bbe63619\"><div class=\"gb-container gb-container-bbe63619\">  <div class=\"wp-block-uagb-image uagb-block-ed88006a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/Medium-OTR-Tire-Dismantling-Machine.webp\" alt=\"\" class=\"uag-image-6020\" width=\"720\" height=\"540\" title=\"Machine de d\u00e9montage de pneus de taille moyenne OTR\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>  <\/div><\/div>  <div class=\"gb-grid-column gb-grid-column-86fb5229\"><div class=\"gb-container gb-container-86fb5229\">  <p class=\"wp-block-paragraph\"><\/p>    <p class=\"gb-headline gb-headline-cdd47ab7 gb-headline-text\">Nom : Machine de d\u00e9montage OTR<br>Puissance : 7,5   5,5 kW<br>Dimensions : 4,35 * 3,8 * 2,4 mm<br>Emballage en caisse en bois : non disponible<br>Poids : 5,6 tonnes<br>Taille du pneu trait\u00e9 : 1400-2000 mm<br>Production : 7-15 minutes par pneu<br>Mat\u00e9riau du couteau : Alliage de carbure de tungst\u00e8ne<\/p>  <\/div><\/div> <\/div>  <div class=\"gb-grid-wrapper gb-grid-wrapper-01d74783\"> <div class=\"gb-grid-column gb-grid-column-a7981a44\"><div class=\"gb-container gb-container-a7981a44\">  <div class=\"wp-block-uagb-image uagb-block-9b1a865a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-tire-recycling-2.webp\" alt=\"\" class=\"uag-image-6025\" width=\"720\" height=\"540\" title=\"Recyclage de pneus OTR\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>  <\/div><\/div>  <div class=\"gb-grid-column gb-grid-column-41d3d476\"><div class=\"gb-container gb-container-41d3d476\">  <p class=\"wp-block-paragraph\"><\/p>    <p class=\"gb-headline gb-headline-dc1c76a6 gb-headline-text\">Nom : Machine de d\u00e9montage de pneus OTR<br>Puissance : 30,5 kW<br>Dimensions : 7,25\u00d73,8\u00d72,98 mm<br>Emballage en caisse en bois : non disponible<br>Poids : 9900 kg<br>Taille du pneu trait\u00e9 : R35-R63<br>Production : 10-30 minutes\/pi\u00e8ce<br>Mat\u00e9riau de l'outil de coupe : Alliage de carbure de tungst\u00e8ne<\/p>  <\/div><\/div> <\/div>   <p class=\"gb-headline gb-headline-805fcab2 gb-headline-text translation-block\"><strong>Vid\u00e9o de <strong>Machine de d\u00e9montage OTR<\/strong><\/strong><\/p>   <div class=\"gb-container gb-container-2a4700c6\">  <figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe loading=\"lazy\" title=\"OTR Dismantling Machine | Efficient OTR Tire Cutting &amp; Dismantling for Recycling\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/1ETQcGR7dUs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div><\/figure>  <\/div>   <p class=\"gb-headline gb-headline-33e30af7 gb-headline-text translation-block\"><strong>Principales caract\u00e9ristiques de la machine de d\u00e9montage OTR<\/strong><\/p>    <p class=\"gb-headline gb-headline-34376011 gb-headline-text\">1. Structure robuste con\u00e7ue pour le d\u00e9montage de gros pneus OTR<br>2. Haute efficacit\u00e9 dans la s\u00e9paration des talons de pneus et des composants en fil d'acier<br>3. Fonctionnement stable avec une puissance forte et des exigences de maintenance faibles<br>4. Facile \u00e0 utiliser avec des performances de travail s\u00fbres et fiables<br>5. Convient aux usines de recyclage de pneus miniers, tout-terrain et de gros camions<br>6. Am\u00e9liore la productivit\u00e9 et r\u00e9duit le co\u00fbt de la main-d'\u0153uvre pour le traitement des pneus OTR<\/p>    <p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonction et application La machine de d\u00e9montage OTR est con\u00e7ue pour couper et s\u00e9parer l'OTR complet<\/p>","protected":false},"author":1,"featured_media":6017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1,91,93],"tags":[],"class_list":["post-6013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-products","category-rubber-tyre-recycling-plant","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"uagb_featured_image_src":{"full":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine.webp",720,540,false],"thumbnail":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine-150x150.webp",150,150,true],"medium":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine-300x225.webp",300,225,true],"medium_large":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine.webp",720,540,false],"large":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine.webp",720,540,false],"trp-custom-language-flag":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine-16x12.webp",16,12,true],"1536x1536":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine.webp",720,540,false],"2048x2048":["https:\/\/www.shuliygroup.com\/wp-content\/uploads\/2026\/02\/OTR-Dismantling-Machine.webp",720,540,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.shuliygroup.com\/fr\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Function and Application The OTR dismantling machine is designed to cut and separate complete OTR","_links":{"self":[{"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/posts\/6013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/comments?post=6013"}],"version-history":[{"count":0,"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/posts\/6013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/media\/6017"}],"wp:attachment":[{"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/media?parent=6013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/categories?post=6013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shuliygroup.com\/fr\/wp-json\/wp\/v2\/tags?post=6013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}